{"id":7,"date":"2022-07-27T09:42:51","date_gmt":"2022-07-27T01:42:51","guid":{"rendered":"https:\/\/blog.ubuntu.oracle.moneng.ink\/?p=7"},"modified":"2022-07-27T09:42:51","modified_gmt":"2022-07-27T01:42:51","slug":"wordpress%e5%bc%80%e7%af%87","status":"publish","type":"post","link":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/2022\/07\/27\/wordpress%e5%bc%80%e7%af%87\/","title":{"rendered":"WordPress\u5f00\u7bc7"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u611f\u8c22\uff0c\u611f\u8c22\u7532\u9aa8\u4e91\uff0c\u611f\u8c22\u5b9d\u5854\u9762\u677f\uff0c\u611f\u8c22\u73b0\u4ee3\u7f51\u7edc\u6280\u672f\uff01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4e5f\u8bb8\uff0c\u8fd9\u4ec5\u662f\u5f00\u59cb\uff0c\u4e5f\u8bb8\u8fd9\u5c06\u662f\u7ed3\u675f\u2026\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u611f\u8c22\uff0c\u611f\u8c22\u7532\u9aa8\u4e91\uff0c\u611f\u8c22\u5b9d\u5854\u9762\u677f\uff0c\u611f\u8c22\u73b0\u4ee3\u7f51\u7edc\u6280\u672f\uff01 \u4e5f\u8bb8\uff0c\u8fd9\u4ec5\u662f\u5f00\u59cb\uff0c\u4e5f\u8bb8\u8fd9\u5c06\u662f\u7ed3\u675f\u2026\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/posts\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":1,"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/posts\/7\/revisions"}],"predecessor-version":[{"id":8,"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/posts\/7\/revisions\/8"}],"wp:attachment":[{"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/media?parent=7"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/categories?post=7"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ubuntu.oracle.moneng.ink\/index.php\/wp-json\/wp\/v2\/tags?post=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}